{"id":2025,"date":"2022-05-10T15:33:45","date_gmt":"2022-05-10T13:33:45","guid":{"rendered":"https:\/\/pieron.international\/?page_id=2025"},"modified":"2022-09-12T12:30:49","modified_gmt":"2022-09-12T10:30:49","slug":"onlinebewerbung","status":"publish","type":"page","link":"https:\/\/pieron.international\/en\/onlinebewerbung\/","title":{"rendered":"Online application"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Vielen Dank f\u00fcr Ihr Interesse an einer Karriere in unserem Unternehmen.<\/p>\n\n\n\n<p class=\"has-text-color wp-block-paragraph\" style=\"color:#000000b8\">F\u00fcllen Sie bitte das folgende Bewerbungsformular aus. Ihre vollst\u00e4ndigen Bewerbungsunterlagen k\u00f6nnen Sie am Ende dieses Formulars als PDF-Datei (bis max. 1,5 MB) mitschicken.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nach intensiver Durchsicht Ihrer Unterlagen werden wir uns schriftlich mit Ihnen in Verbindung setzen.<\/p>\n\n\n<div class=\"wpforms-container wpforms-block\" id=\"wpforms-2028\"><form id=\"wpforms-form-2028\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"2028\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/en\/wp-json\/wp\/v2\/pages\/2025?wpforms_form_id=2028\" data-token=\"11862579f2169924d1c586939f894754\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-2028-field_1-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-2028-field_1\">Ihr Name<\/label><input type=\"text\" id=\"wpforms-2028-field_1\" class=\"wpforms-field-large\" name=\"wpforms[fields][1]\" ><\/div><div id=\"wpforms-2028-field_2-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-2028-field_2\">Ihre E-Mail <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-2028-field_2\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][2]\" spellcheck=\"false\" required><\/div><div id=\"wpforms-2028-field_3-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-2028-field_3\">Ihre Nachricht <span class=\"wpforms-required-label\">*<\/span><\/label><textarea id=\"wpforms-2028-field_3\" class=\"wpforms-field-large wpforms-field-required\" name=\"wpforms[fields][3]\" required><\/textarea><\/div><div id=\"wpforms-2028-field_4-container\" class=\"wpforms-field wpforms-field-file-upload\" data-field-id=\"4\"><label class=\"wpforms-field-label\" for=\"wpforms-2028-field_4\">Datei hochladen<\/label><div\n\t\tclass=\"wpforms-uploader\"\n\t\tdata-field-id=\"4\"\n\t\tdata-form-id=\"2028\"\n\t\tdata-input-name=\"wpforms_2028_4\"\n\t\tdata-extensions=\"pdf\"\n\t\tdata-max-size=\"6291456\"\n\t\tdata-max-file-number=\"4\"\n\t\tdata-post-max-size=\"6442450944\"\n\t\tdata-max-parallel-uploads=\"4\"\n\t\tdata-parallel-uploads=\"true\"\n\t\tdata-file-chunk-size=\"2097152\">\n\t<div class=\"dz-message\">\n\t\t<svg viewBox=\"0 0 1024 1024\" focusable=\"false\" data-icon=\"inbox\" width=\"50px\" height=\"50px\" fill=\"currentColor\" aria-hidden=\"true\">\n\t\t\t<path d=\"M885.2 446.3l-.2-.8-112.2-285.1c-5-16.1-19.9-27.2-36.8-27.2H281.2c-17 0-32.1 11.3-36.9 27.6L139.4 443l-.3.7-.2.8c-1.3 4.9-1.7 9.9-1 14.8-.1 1.6-.2 3.2-.2 4.8V830a60.9 60.9 0 0 0 60.8 60.8h627.2c33.5 0 60.8-27.3 60.9-60.8V464.1c0-1.3 0-2.6-.1-3.7.4-4.9 0-9.6-1.3-14.1zm-295.8-43l-.3 15.7c-.8 44.9-31.8 75.1-77.1 75.1-22.1 0-41.1-7.1-54.8-20.6S436 441.2 435.6 419l-.3-15.7H229.5L309 210h399.2l81.7 193.3H589.4zm-375 76.8h157.3c24.3 57.1 76 90.8 140.4 90.8 33.7 0 65-9.4 90.3-27.2 22.2-15.6 39.5-37.4 50.7-63.6h156.5V814H214.4V480.1z\"><\/path>\n\t\t<\/svg>\n\t\t<span class=\"modern-title\">Click or drag files to this area to upload.<\/span>\n\n\t\t\t\t\t<span class=\"modern-hint\">You can upload up to 4 files.<\/span>\n\t\t\t<\/div>\n<\/div>\n<input\n\t\ttype=\"text\"\n\t\tautocomplete=\"off\"\n\t\tclass=\"dropzone-input\"\n\t\tstyle=\"position:absolute!important;clip:rect(0,0,0,0)!important;height:1px!important;width:1px!important;border:0!important;overflow:hidden!important;padding:0!important;margin:0!important;\"\n\t\tid=\"wpforms-2028-field_4\"\n\t\tname=\"wpforms_2028_4\" \t\tvalue=\"\">\n<div class=\"wpforms-field-description\">PDF-Dateien (max. 4x 1,5 MB) hinzuf\u00fcgen und mitsenden. Wenn Sie alle Unterlagen in einem PDF haben, freuen wir uns ebenso:\r\n\r\n1. Anschreiben, 2. Lebenslauf, 3. Zeugnisse, 4. Sonstiges oder alles in einer PDF<\/div><\/div><div id=\"wpforms-2028-field_5-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-id=\"5\"><label class=\"wpforms-field-label\" for=\"wpforms-2028-field_5\">Checkboxen <span class=\"wpforms-required-label\">*<\/span><\/label><ul id=\"wpforms-2028-field_5\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-2028-field_5_1\" name=\"wpforms[fields][5][]\" value=\"Ich akzeptiere die Datenschutzerkl\u00e4rung\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-2028-field_5_1\">Ich akzeptiere die Datenschutzerkl\u00e4rung<\/label><\/li><\/ul><div class=\"wpforms-field-description\">Mit dem Absenden dieses Formulars erkl\u00e4ren Sie sich mit der Speicherung und Verarbeitung Ihrer Daten durch uns einverstanden. Die <a href=\"https:\/\/pieron.international\/datenschutz\">Datenschutzerkl\u00e4rung<\/a> (Abschnitt &#8222;7. Onlinebewerbung \u00fcber unsere Webseite&#8220;) auf der Webseite habe ich zu Kenntnis genommen.<\/div><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-recaptcha-container wpforms-is-hcaptcha\" ><div class=\"g-recaptcha\" data-sitekey=\"e1c0c555-72a9-412d-8a54-cfbfcbb38090\"><\/div><input type=\"text\" name=\"g-recaptcha-hidden\" class=\"wpforms-recaptcha-hidden\" style=\"position:absolute!important;clip:rect(0,0,0,0)!important;height:1px!important;width:1px!important;border:0!important;overflow:hidden!important;padding:0!important;margin:0!important;\" data-rule-hcaptcha=\"1\"><\/div><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"2028\"><input type=\"hidden\" name=\"wpforms[author]\" value=\"1\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-2028\" class=\"wpforms-submit\" data-alt-text=\"Senden\u2026\" data-submit-text=\"Absenden\" aria-live=\"assertive\" value=\"wpforms-submit\">Absenden<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/pieron.international\/wp-content\/plugins\/wpforms\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\" title=\"\"><\/div><\/form><\/div>  <!-- .wpforms-container -->","protected":false},"excerpt":{"rendered":"<p>Vielen Dank f\u00fcr Ihr Interesse an einer Karriere in unserem Unternehmen. F\u00fcllen Sie bitte das folgende Bewerbungsformular aus. Ihre vollst\u00e4ndigen Bewerbungsunterlagen k\u00f6nnen Sie am Ende dieses Formulars als PDF-Datei (bis max. 1,5 MB) mitschicken. Nach intensiver Durchsicht Ihrer Unterlagen werden wir uns schriftlich mit Ihnen in Verbindung setzen.<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"qubely_global_settings":"","qubely_interactions":"","pgc_sgb_lightbox_settings":"","footnotes":""},"class_list":["post-2025","page","type-page","status-publish","hentry"],"blocksy_meta":{"styles_descriptor":{"styles":{"desktop":"","tablet":"","mobile":""},"google_fonts":[],"version":6}},"_links":{"self":[{"href":"https:\/\/pieron.international\/en\/wp-json\/wp\/v2\/pages\/2025","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pieron.international\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/pieron.international\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/pieron.international\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/pieron.international\/en\/wp-json\/wp\/v2\/comments?post=2025"}],"version-history":[{"count":5,"href":"https:\/\/pieron.international\/en\/wp-json\/wp\/v2\/pages\/2025\/revisions"}],"predecessor-version":[{"id":35710,"href":"https:\/\/pieron.international\/en\/wp-json\/wp\/v2\/pages\/2025\/revisions\/35710"}],"wp:attachment":[{"href":"https:\/\/pieron.international\/en\/wp-json\/wp\/v2\/media?parent=2025"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}